{"id":3149,"date":"2023-04-05T09:59:11","date_gmt":"2023-04-05T07:59:11","guid":{"rendered":"http:\/\/event-box.be\/?p=3149"},"modified":"2025-07-16T16:42:31","modified_gmt":"2025-07-16T14:42:31","slug":"la-petanque-petite-histoire-par-event-box","status":"publish","type":"post","link":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/","title":{"rendered":"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0!"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">Tout le monde conna\u00eet ce jeu populaire qui sent le pastis et le Sud de la France&nbsp;: la p\u00e9tanque&nbsp;! Mais qui peut dire d\u2019o\u00f9 elle vient exactement&nbsp;? Qui peut raconter son histoire&nbsp;? Et quels sont ses bienfaits pour la sant\u00e9 (car oui, ils sont nombreux&nbsp;!)&nbsp;? Chez Event Box, nous avons choisi de remettre au go\u00fbt du jour ce jeu vieux de cent ans&#8230; Voire plus&nbsp;! D\u00e9couverte de l\u2019histoire de la p\u00e9tanque, un loisir qui faisait d\u00e9j\u00e0 r\u00eaver nos anc\u00eatres gaulois\u2026<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"965\" height=\"664\" src=\"http:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2023-04-05-09_54_11-Galerie-BOOGLE-au-jardin-BOOGLE\u00ae-La-petanque-Booster-de-convivialite-\u2014-Moz.png\" alt=\"\" class=\"wp-image-3151\" srcset=\"https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2023-04-05-09_54_11-Galerie-BOOGLE-au-jardin-BOOGLE\u00ae-La-petanque-Booster-de-convivialite-\u2014-Moz.png 965w, https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2023-04-05-09_54_11-Galerie-BOOGLE-au-jardin-BOOGLE\u00ae-La-petanque-Booster-de-convivialite-\u2014-Moz-300x206.png 300w, https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2023-04-05-09_54_11-Galerie-BOOGLE-au-jardin-BOOGLE\u00ae-La-petanque-Booster-de-convivialite-\u2014-Moz-768x528.png 768w, https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2023-04-05-09_54_11-Galerie-BOOGLE-au-jardin-BOOGLE\u00ae-La-petanque-Booster-de-convivialite-\u2014-Moz-700x482.png 700w\" sizes=\"(max-width: 965px) 100vw, 965px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\"><strong>RETOUR AUX ORIGINES DE LA P\u00c9TANQUE\u00a0<\/strong><\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de se nommer \u00ab&nbsp;p\u00e9tanque&nbsp;\u00bb, ce jeu s\u2019appelait simplement \u00ab&nbsp;jeu de boules&nbsp;\u00bb. Et l\u00e0, ses origines remontent au moins \u00e0 la conqu\u00eate de la Gaule. \u00c0 cette \u00e9poque, les boules \u00e9taient faites d\u2019argile, puis de pierre, de bois et d\u2019acier. Le but du jeu reste assez flou&nbsp;: les boules \u00e9taient lanc\u00e9es par les joueurs dans une m\u00eame direction. Ceux-ci devaient prendre de l\u2019\u00e9lan pour l\u2019envoyer plus loin que celles de l\u2019adversaire, mais nous n\u2019en savons pas beaucoup plus\u2026&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e8s la renaissance, ce jeu de boules c\u00f4toie de pr\u00e8s le jeu de paume, qui donnera naissance \u00e0 notre c\u00e9l\u00e8bre tennis. Ils sont alors les deux jeux pr\u00e9f\u00e9r\u00e9s de la noblesse fran\u00e7aise&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est seulement en 1907, \u00e0 La Ciotat, que la premi\u00e8re r\u00e9f\u00e9rence \u00e0 la p\u00e9tanque appara\u00eet. Alors qu\u2019il est atteint de rhumatismes l\u2019emp\u00eachant de pratiquer correctement le jeu de boules, le champion Lenoir invente alors de nouvelles r\u00e8gles. Plus question de sauter ou de courir, ni de lancer sa boule le plus loin possible. D\u00e9sormais, il faudra se tenir les pieds serr\u00e9s dans un cercle, envoyer un cochonnet \u00e0 5 ou 6 m\u00e8tres maximum et tenter d\u2019approcher ensuite ses boules le plus pr\u00e8s possible de ce cochonnet. \u00c0 l\u2019\u00e9poque, cette fa\u00e7on particuli\u00e8re de positionner ses pieds s\u2019appelait \u00ab&nbsp;avoir les pieds tanqu\u00e9s&nbsp;\u00bb, c\u2019est-\u00e0-dire profond\u00e9ment ancr\u00e9s dans le sol.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette expression, \u00ab&nbsp;Pieds tanqu\u00e9s&nbsp;\u00bb, a rapidement donn\u00e9 son nom \u00e0 la p\u00e9tanque mais aussi ses r\u00e8gles. Et si la p\u00e9tanque coule dans les veines de la Provence, c\u2019est parce que ce jour de 1907, sur la place de la Ciotat o\u00f9 s\u2019est d\u00e9roul\u00e9e l\u2019histoire, les propri\u00e9taires du caf\u00e9 d\u2019en face ayant assist\u00e9 \u00e0 la sc\u00e8ne ont d\u00e9cid\u00e9 d\u2019\u00e9tablir et de consigner les r\u00e8gles d\u2019or de ce nouveau sport national. Des r\u00e8gles qui restent pratiquement inchang\u00e9es depuis\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\">LES BIENFAITS D&rsquo;UN JEU CENTENAIRE<\/mark><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si la p\u00e9tanque vous rappelle les vacances au soleil, sachez qu\u2019elle est aussi un sport complet qui fait travailler bon nombre de comp\u00e9tences importantes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">La p\u00e9tanque entretien votre physique<\/mark><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c7a vous \u00e9tonne&nbsp;? Pourtant, la p\u00e9tanque est bel et bien un sport physique qui, au fil du temps, vous aide \u00e0 travailler votre \u00e9quilibre, votre souplesse et votre agilit\u00e9. Particuli\u00e8rement b\u00e9n\u00e9fique pour les articulations, la p\u00e9tanque est d\u2019ailleurs conseill\u00e9e pour les personnes \u00e2g\u00e9es, en manque d\u2019exercice, ou pour les personnes en revalidation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">La p\u00e9tanque d\u00e9veloppe votre mental et votre strat\u00e9gie<\/mark><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ok, la p\u00e9tanque, c\u2019est avant tout le meilleur moyen de d\u00e9guster un bon pastis pendant que le barbec chauffe\u2026 Mais pas seulement. C\u2019est aussi un sport minutieux qui se joue avant tout avec la t\u00eate. La pr\u00e9cision des gestes, la force des tirs mais aussi la strat\u00e9gie \u00e0 adopter pour gagner la manche, autant de capacit\u00e9s qui se d\u00e9velopperont au fil des parties. Dans quelle direction tirer&nbsp;? Se rapprocher du cochonnet ou \u00e9loigner ses adversaires&nbsp;? Une concentration \u00e0 toute \u00e9preuve est de mise pour gagner un maximum de points&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">La p\u00e9tanque vous aide \u00e0 travailler votre adresse<\/mark><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Alors, tu tires ou tu pointes&nbsp;?!&nbsp;\u00bb Telle est la question cruciale \u00e0 la p\u00e9tanque\u2026 Si tout est une affaire de choix strat\u00e9gique, c\u2019est \u00e9galement une grande histoire de pr\u00e9cision. Quel que soit votre choix, il faudra viser juste et surtout coordonner vos gestes pour \u00e9viter de finir fanny&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">La p\u00e9tanque, ce beau moment de partage<\/mark><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si la p\u00e9tanque est riche pour le corps, elle est aussi tr\u00e8s riche pour l\u2019esprit. Ce sport, \u00e9vocateur de d\u00e9tente et de soleil, se joue toujours en \u00e9quipe et en face \u00e0 face, avec, le plus souvent, beaucoup de spectateurs autour pour encourager les joueurs\u2026 De quoi passer des moments privil\u00e9gi\u00e9s en famille, entre amis ou entre coll\u00e8gues autour d\u2019un sport sympa, accessible et ultra convivial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\">LA P\u00c9TANQUE PAR EVENT BOX<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous comprenez maintenant beaucoup mieux pourquoi, chez Event Box, nous avons voulu remettre ce sport en lumi\u00e8re et lui rendre ses lettres de noblesse. Notre petit plus&nbsp;? Avec Event Box, la p\u00e9tanque se joue aussi en int\u00e9rieur&nbsp;!&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\"><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-white-color\">JE CONTACTE EVENT BOX POUR LOUER UN TERRAIN DE P\u00c9TANQUE<\/mark><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez l&rsquo;histoire de ce jeu mythique qu&rsquo;est la p\u00e9tanque et pourquoi Event Box a choisi de le remettre au go\u00fbt du jour.<\/p>\n","protected":false},"author":2,"featured_media":4981,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[60,51],"tags":[],"class_list":["post-3149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-nos-services"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0! - Event-box<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l&#039;histoire du c\u00e9l\u00e8bre jeu de la p\u00e9tanque et pourquoi Event Box a choisi de la remettre au go\u00fbt du jour.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0! - Event-box\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l&#039;histoire du c\u00e9l\u00e8bre jeu de la p\u00e9tanque et pourquoi Event Box a choisi de la remettre au go\u00fbt du jour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/\" \/>\n<meta property=\"og:site_name\" content=\"Event-box\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100076146701741\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-05T07:59:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T14:42:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Event Box\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Event Box\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/\"},\"author\":{\"name\":\"Event Box\",\"@id\":\"https:\\\/\\\/event-box.be\\\/#\\\/schema\\\/person\\\/1c151ba0453659eb15066ab40896821a\"},\"headline\":\"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0!\",\"datePublished\":\"2023-04-05T07:59:11+00:00\",\"dateModified\":\"2025-07-16T14:42:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/\"},\"wordCount\":880,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/event-box.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png\",\"articleSection\":[\"Blog\",\"Nos services\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/\",\"url\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/\",\"name\":\"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0! - Event-box\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/event-box.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png\",\"datePublished\":\"2023-04-05T07:59:11+00:00\",\"dateModified\":\"2025-07-16T14:42:31+00:00\",\"description\":\"D\u00e9couvrez l'histoire du c\u00e9l\u00e8bre jeu de la p\u00e9tanque et pourquoi Event Box a choisi de la remettre au go\u00fbt du jour.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#primaryimage\",\"url\":\"https:\\\/\\\/event-box.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png\",\"contentUrl\":\"https:\\\/\\\/event-box.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png\",\"width\":512,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/2023\\\/04\\\/05\\\/la-petanque-petite-histoire-par-event-box\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/event-box.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/event-box.be\\\/#website\",\"url\":\"https:\\\/\\\/event-box.be\\\/\",\"name\":\"Event-box\",\"description\":\"Cr\u00e9ateur d ambiance\",\"publisher\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/event-box.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/event-box.be\\\/#organization\",\"name\":\"Event-box\",\"url\":\"https:\\\/\\\/event-box.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/event-box.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/event-box.be\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Event-box-bleu-a-lendroit-PNG-2-002-1.png\",\"contentUrl\":\"https:\\\/\\\/event-box.be\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Event-box-bleu-a-lendroit-PNG-2-002-1.png\",\"width\":1692,\"height\":580,\"caption\":\"Event-box\"},\"image\":{\"@id\":\"https:\\\/\\\/event-box.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100076146701741\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/event-box.be\\\/#\\\/schema\\\/person\\\/1c151ba0453659eb15066ab40896821a\",\"name\":\"Event Box\",\"sameAs\":[\"http:\\\/\\\/www.event-box.be\"],\"url\":\"https:\\\/\\\/event-box.be\\\/index.php\\\/author\\\/event-box\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0! - Event-box","description":"D\u00e9couvrez l'histoire du c\u00e9l\u00e8bre jeu de la p\u00e9tanque et pourquoi Event Box a choisi de la remettre au go\u00fbt du jour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/","og_locale":"fr_FR","og_type":"article","og_title":"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0! - Event-box","og_description":"D\u00e9couvrez l'histoire du c\u00e9l\u00e8bre jeu de la p\u00e9tanque et pourquoi Event Box a choisi de la remettre au go\u00fbt du jour.","og_url":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/","og_site_name":"Event-box","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100076146701741","article_published_time":"2023-04-05T07:59:11+00:00","article_modified_time":"2025-07-16T14:42:31+00:00","og_image":[{"width":512,"height":687,"url":"https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png","type":"image\/png"}],"author":"Event Box","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Event Box","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#article","isPartOf":{"@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/"},"author":{"name":"Event Box","@id":"https:\/\/event-box.be\/#\/schema\/person\/1c151ba0453659eb15066ab40896821a"},"headline":"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0!","datePublished":"2023-04-05T07:59:11+00:00","dateModified":"2025-07-16T14:42:31+00:00","mainEntityOfPage":{"@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/"},"wordCount":880,"commentCount":0,"publisher":{"@id":"https:\/\/event-box.be\/#organization"},"image":{"@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#primaryimage"},"thumbnailUrl":"https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png","articleSection":["Blog","Nos services"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/","url":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/","name":"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0! - Event-box","isPartOf":{"@id":"https:\/\/event-box.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#primaryimage"},"image":{"@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#primaryimage"},"thumbnailUrl":"https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png","datePublished":"2023-04-05T07:59:11+00:00","dateModified":"2025-07-16T14:42:31+00:00","description":"D\u00e9couvrez l'histoire du c\u00e9l\u00e8bre jeu de la p\u00e9tanque et pourquoi Event Box a choisi de la remettre au go\u00fbt du jour.","breadcrumb":{"@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#primaryimage","url":"https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png","contentUrl":"https:\/\/event-box.be\/wp-content\/uploads\/2023\/04\/2025-07-16-16_41_38-Lumys-Ete-2024-au-Musee-de-la-Vie-Wallonne-\u2014-Mozilla-Firefox.png","width":512,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/event-box.be\/index.php\/2023\/04\/05\/la-petanque-petite-histoire-par-event-box\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/event-box.be\/"},{"@type":"ListItem","position":2,"name":"La p\u00e9tanque : petite histoire\u2026 par Event Box\u00a0!"}]},{"@type":"WebSite","@id":"https:\/\/event-box.be\/#website","url":"https:\/\/event-box.be\/","name":"Event-box","description":"Cr\u00e9ateur d ambiance","publisher":{"@id":"https:\/\/event-box.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/event-box.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/event-box.be\/#organization","name":"Event-box","url":"https:\/\/event-box.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/event-box.be\/#\/schema\/logo\/image\/","url":"https:\/\/event-box.be\/wp-content\/uploads\/2024\/09\/Event-box-bleu-a-lendroit-PNG-2-002-1.png","contentUrl":"https:\/\/event-box.be\/wp-content\/uploads\/2024\/09\/Event-box-bleu-a-lendroit-PNG-2-002-1.png","width":1692,"height":580,"caption":"Event-box"},"image":{"@id":"https:\/\/event-box.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100076146701741"]},{"@type":"Person","@id":"https:\/\/event-box.be\/#\/schema\/person\/1c151ba0453659eb15066ab40896821a","name":"Event Box","sameAs":["http:\/\/www.event-box.be"],"url":"https:\/\/event-box.be\/index.php\/author\/event-box\/"}]}},"_links":{"self":[{"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/posts\/3149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/comments?post=3149"}],"version-history":[{"count":4,"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/posts\/3149\/revisions"}],"predecessor-version":[{"id":3288,"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/posts\/3149\/revisions\/3288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/media\/4981"}],"wp:attachment":[{"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/media?parent=3149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/categories?post=3149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/event-box.be\/index.php\/wp-json\/wp\/v2\/tags?post=3149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}